{"id":3306,"date":"2023-02-10T04:12:53","date_gmt":"2023-02-10T04:12:53","guid":{"rendered":"https:\/\/homelux.my.id\/?page_id=3306"},"modified":"2023-05-04T04:00:05","modified_gmt":"2023-05-04T04:00:05","slug":"aloft-bali-kuta","status":"publish","type":"page","link":"https:\/\/homelux.co.id\/id\/commercial-building-2\/aloft-bali-kuta\/","title":{"rendered":"Aloft Bali Kuta"},"content":{"rendered":"<div data-elementor-type=\"wp-page\" data-elementor-id=\"3306\" class=\"elementor elementor-3306\">\n\t\t\t\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-92d67bf elementor-section-height-min-height elementor-section-full_width elementor-section-height-default elementor-section-items-middle wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no\" data-id=\"92d67bf\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-32fe216a\" data-id=\"32fe216a\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2e0fe75 wpr-dual-heading-desc-top elementor-widget elementor-widget-wpr-dual-color-heading\" data-id=\"2e0fe75\" data-element_type=\"widget\" data-widget_type=\"wpr-dual-color-heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t<div class=\"wpr-dual-heading-wrap\">\n\t\t\t\t<div class=\"wpr-dual-title-wrap\">\n\t\t\t\t\t<h2 class=\"wpr-dual-title\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"first\">Aloft Hotel<\/span>\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"second\">Bali Kuta<\/span>\n\t\t\t\t\t\t\t\t\t\t<\/h2>\n\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<div class=\"wpr-dual-heading-description\" >PT. Indal Aluminium Industries Tbk.<\/div>\n\t\t\t\t\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-eb120b3 elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no\" data-id=\"eb120b3\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-100112f2\" data-id=\"100112f2\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-1c9b5ae elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no elementor-invisible\" data-id=\"1c9b5ae\" data-element_type=\"section\" data-settings=\"{&quot;animation&quot;:&quot;fadeInUp&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-7e4508aa\" data-id=\"7e4508aa\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-211b2f8c elementor-widget__width-initial elementor-widget elementor-widget-elementskit-heading\" data-id=\"211b2f8c\" data-element_type=\"widget\" data-widget_type=\"elementskit-heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<div class=\"ekit-wid-con\" ><div class=\"ekit-heading elementskit-section-title-wraper text_center   ekit_heading_tablet-   ekit_heading_mobile-\"><h3 class=\"elementskit-section-subtitle\">\n\t\t\t\t\t\tBangunan Komersial\n\t\t\t\t\t<\/h3><h2 class=\"ekit-heading--title elementskit-section-title\">Selamat datang di Aloft Bali Kuta<\/h2><\/div><\/div>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-049e5d4 elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no\" data-id=\"049e5d4\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-687e6a1\" data-id=\"687e6a1\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1c60dc4 elementor-arrows-position-inside elementor-pagination-position-outside elementor-widget elementor-widget-image-carousel\" data-id=\"1c60dc4\" data-element_type=\"widget\" data-settings=\"{&quot;slides_to_show&quot;:&quot;1&quot;,&quot;navigation&quot;:&quot;both&quot;,&quot;autoplay&quot;:&quot;yes&quot;,&quot;pause_on_hover&quot;:&quot;yes&quot;,&quot;pause_on_interaction&quot;:&quot;yes&quot;,&quot;autoplay_speed&quot;:5000,&quot;infinite&quot;:&quot;yes&quot;,&quot;effect&quot;:&quot;slide&quot;,&quot;speed&quot;:500}\" data-widget_type=\"image-carousel.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<style>\/*! elementor - v3.18.0 - 20-12-2023 *\/\n.elementor-widget-image-carousel .swiper,.elementor-widget-image-carousel .swiper-container{position:static}.elementor-widget-image-carousel .swiper-container .swiper-slide figure,.elementor-widget-image-carousel .swiper .swiper-slide figure{line-height:inherit}.elementor-widget-image-carousel .swiper-slide{text-align:center}.elementor-image-carousel-wrapper:not(.swiper-container-initialized):not(.swiper-initialized) .swiper-slide{max-width:calc(100% \/ var(--e-image-carousel-slides-to-show, 3))}<\/style>\t\t<div class=\"elementor-image-carousel-wrapper swiper-container\" dir=\"ltr\">\n\t\t\t<div class=\"elementor-image-carousel swiper-wrapper\" aria-live=\"off\">\n\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"1 of 3\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/homelux.co.id\/wp-content\/uploads\/2023\/02\/1-14.jpg\" alt=\"1\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"2 of 3\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/homelux.co.id\/wp-content\/uploads\/2023\/02\/2-15.jpg\" alt=\"2\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"3 of 3\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/homelux.co.id\/wp-content\/uploads\/2023\/02\/4-11.jpg\" alt=\"4\" \/><\/figure><\/div>\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-prev\" role=\"button\" tabindex=\"0\">\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-chevron-left\"><\/i>\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-next\" role=\"button\" tabindex=\"0\">\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-chevron-right\"><\/i>\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<div class=\"swiper-pagination\"><\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f18e7cc elementor-widget elementor-widget-spacer\" data-id=\"f18e7cc\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<style>\/*! elementor - v3.18.0 - 20-12-2023 *\/\n.elementor-column .elementor-spacer-inner{height:var(--spacer-size)}.e-con{--container-widget-width:100%}.e-con-inner>.elementor-widget-spacer,.e-con>.elementor-widget-spacer{width:var(--container-widget-width,var(--spacer-size));--align-self:var(--container-widget-align-self,initial);--flex-shrink:0}.e-con-inner>.elementor-widget-spacer>.elementor-widget-container,.e-con>.elementor-widget-spacer>.elementor-widget-container{height:100%;width:100%}.e-con-inner>.elementor-widget-spacer>.elementor-widget-container>.elementor-spacer,.e-con>.elementor-widget-spacer>.elementor-widget-container>.elementor-spacer{height:100%}.e-con-inner>.elementor-widget-spacer>.elementor-widget-container>.elementor-spacer>.elementor-spacer-inner,.e-con>.elementor-widget-spacer>.elementor-widget-container>.elementor-spacer>.elementor-spacer-inner{height:var(--container-widget-height,var(--spacer-size))}.e-con-inner>.elementor-widget-spacer.elementor-widget-empty,.e-con>.elementor-widget-spacer.elementor-widget-empty{position:relative;min-height:22px;min-width:22px}.e-con-inner>.elementor-widget-spacer.elementor-widget-empty .elementor-widget-empty-icon,.e-con>.elementor-widget-spacer.elementor-widget-empty .elementor-widget-empty-icon{position:absolute;top:0;bottom:0;left:0;right:0;margin:auto;padding:0;width:22px;height:22px}<\/style>\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-02b577e elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no\" data-id=\"02b577e\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-e9473fd\" data-id=\"e9473fd\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-60dfd49 wpr-dual-heading-icon-top elementor-widget elementor-widget-wpr-dual-color-heading\" data-id=\"60dfd49\" data-element_type=\"widget\" data-widget_type=\"wpr-dual-color-heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t<div class=\"wpr-dual-heading-wrap\">\n\t\t\t\t<div class=\"wpr-dual-title-wrap\">\n\t\t\t\t\t<h5 class=\"wpr-dual-title\">\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t<\/h5>\n\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<div class=\"wpr-dual-heading-description\" >Bali<\/div>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<div class=\"wpr-dual-heading-icon-wrap\">\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-search-location\"><\/i>\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-77fdf4f\" data-id=\"77fdf4f\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-11d1193 wpr-dual-heading-icon-top elementor-widget elementor-widget-wpr-dual-color-heading\" data-id=\"11d1193\" data-element_type=\"widget\" data-widget_type=\"wpr-dual-color-heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t<div class=\"wpr-dual-heading-wrap\">\n\t\t\t\t<div class=\"wpr-dual-title-wrap\">\n\t\t\t\t\t<h5 class=\"wpr-dual-title\">\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t<\/h5>\n\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<div class=\"wpr-dual-heading-description\" >Selesai pada tahun 2022<\/div>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<div class=\"wpr-dual-heading-icon-wrap\">\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"far fa-calendar-check\"><\/i>\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-5b42623\" data-id=\"5b42623\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6238fb2 wpr-dual-heading-icon-top elementor-widget elementor-widget-wpr-dual-color-heading\" data-id=\"6238fb2\" data-element_type=\"widget\" data-widget_type=\"wpr-dual-color-heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t<div class=\"wpr-dual-heading-wrap\">\n\t\t\t\t<div class=\"wpr-dual-title-wrap\">\n\t\t\t\t\t<h5 class=\"wpr-dual-title\">\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t<\/h5>\n\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<div class=\"wpr-dual-heading-description\" >1 Menara, 3 Lantai &amp; 175 Kamar<\/div>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<div class=\"wpr-dual-heading-icon-wrap\">\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"far fa-building\"><\/i>\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-f0297c3\" data-id=\"f0297c3\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-195a2ae wpr-dual-heading-icon-top elementor-widget elementor-widget-wpr-dual-color-heading\" data-id=\"195a2ae\" data-element_type=\"widget\" data-widget_type=\"wpr-dual-color-heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t<div class=\"wpr-dual-heading-wrap\">\n\t\t\t\t<div class=\"wpr-dual-title-wrap\">\n\t\t\t\t\t<h5 class=\"wpr-dual-title\">\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t<\/h5>\n\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<div class=\"wpr-dual-heading-description\" >Produk HOMELUX<\/div>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<div class=\"wpr-dual-heading-icon-wrap\">\n\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" id=\"Layer_1\" x=\"0px\" y=\"0px\" viewbox=\"0 0 384 384\" style=\"enable-background:new 0 0 384 384;\" xml:space=\"preserve\"><g>\t<path d=\"M374.01,383.9c-121.26,0-242.53,0-363.79,0c-7.79-3.06-9.63-9.03-9.62-16.96C0.76,249.92,0.71,132.9,0.71,15.88  c0-11.06,4.04-15.11,15.1-15.11c116.99,0,233.98,0.05,350.97-0.11c7.92-0.01,13.91,1.79,16.95,9.62c0,121.29,0,242.59,0,363.88  C381.9,378.81,378.65,382.05,374.01,383.9z M371.67,371.92c0-120.03,0-239.61,0-359.32c-119.84,0-239.39,0-359.04,0  c0,119.92,0,239.59,0,359.32C132.44,371.92,251.91,371.92,371.67,371.92z\"><\/path>\t<path d=\"M192.11,18.7c52.89,0,105.77,0,158.66,0c10.45,0,14.82,4.34,14.82,14.73c0,105.92,0,211.85,0,317.77  c0,10.18-4.39,14.53-14.64,14.53c-105.9,0-211.8,0-317.7,0c-10.19,0-14.62-4.41-14.62-14.56c0-105.92,0-211.85,0-317.77  c0-10.44,4.3-14.71,14.82-14.71C86.34,18.7,139.23,18.7,192.11,18.7z M30.44,30.49c0,108.08,0,215.69,0,323.41  c52.03,0,103.82,0,155.61,0c0-107.97,0-215.66,0-323.41C134.05,30.49,82.35,30.49,30.44,30.49z M198.1,30.47  c0,108.07,0,215.67,0,323.43c52.01,0,103.8,0,155.64,0c0-107.96,0-215.65,0-323.43C301.75,30.47,250.04,30.47,198.1,30.47z\"><\/path>\t<path d=\"M170.62,123.33c1.95,2,4.38,4.49,6.44,6.59c-39.62,39.63-79.23,79.25-118.8,118.83c-1.83-1.93-4.26-4.51-6.33-6.69  C91.07,202.9,130.68,163.28,170.62,123.33z\"><\/path>\t<path d=\"M36.64,195.19c0-8.35-0.03-16.7,0.01-25.05c0.03-6.27,3.25-8.67,9.09-6.77c5.08,1.65,10.12,3.44,15.22,5.06  c3.58,1.14,5.21,3.44,5.19,7.2c-0.06,13.08-0.06,26.17,0,39.26c0.01,3.77-1.69,6.03-5.26,7.15c-5.22,1.64-10.37,3.48-15.58,5.15  c-5.19,1.67-8.59-0.74-8.64-6.2C36.59,212.38,36.65,203.79,36.64,195.19z M48.46,213.62c6.1-0.83,6.11-0.83,6.11-6.25  c0-8.1,0-16.2,0-24.3c0-5.42,0-5.42-6.11-6.26C48.46,189.09,48.46,201.34,48.46,213.62z\"><\/path>\t<path d=\"M82.11,189.43c-2.16-2.26-4.62-4.85-6.83-7.17c23.6-23.6,47.26-47.27,71.1-71.11c2.14,2.27,4.6,4.86,6.81,7.19  C129.63,141.91,105.96,165.58,82.11,189.43z\"><\/path>\t<path d=\"M140.7,189.23c1.92,1.97,4.35,4.47,6.4,6.58c-21.65,21.65-43.29,43.29-64.89,64.89c-1.81-1.92-4.24-4.49-6.34-6.72  C97.04,232.83,118.69,211.21,140.7,189.23z\"><\/path>\t<path d=\"M325.91,123.16c2.3,2.27,4.84,4.78,7.13,7.04c-39.76,39.77-79.39,79.41-119.08,119.11c-2.32-2.26-4.87-4.76-7.16-7  C246.6,202.49,286.22,162.86,325.91,123.16z\"><\/path>\t<path d=\"M347.58,195.51c0,8.35,0.04,16.7-0.01,25.05c-0.03,5.95-3.37,8.37-8.97,6.55c-5.2-1.69-10.37-3.49-15.57-5.19  c-3.42-1.12-4.96-3.4-4.95-6.99c0.05-13.21,0.04-26.42,0.01-39.63c-0.01-3.43,1.53-5.66,4.78-6.73c5.43-1.79,10.84-3.65,16.29-5.37  c4.96-1.57,8.34,0.86,8.39,6.14C347.65,178.06,347.58,186.79,347.58,195.51z M335.69,213.7c0-12.45,0-24.68,0-36.96  c-6.02,1.17-6.02,1.17-6.03,6.5c0,7.97,0,15.95,0,23.92C329.66,212.51,329.67,212.51,335.69,213.7z\"><\/path>\t<path d=\"M237.6,189.32c-2.08-2.1-4.52-4.56-6.63-6.68c23.74-23.73,47.39-47.37,71.07-71.05c1.87,2.01,4.29,4.61,6.38,6.86  C285.19,141.7,261.55,165.36,237.6,189.32z\"><\/path>\t<path d=\"M238,261.14c-2.34-2.22-4.94-4.67-7.32-6.93c21.79-21.79,43.37-43.38,64.92-64.93c2.19,2.36,4.66,5.03,6.87,7.4  C281.25,217.9,259.58,239.56,238,261.14z\"><\/path><\/g><\/svg>\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-0e62fd9 elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no\" data-id=\"0e62fd9\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-e922091\" data-id=\"e922091\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-05fe462 elementor-widget elementor-widget-spacer\" data-id=\"05fe462\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1406451 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"1406451\" data-element_type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<style>\/*! elementor - v3.18.0 - 20-12-2023 *\/\n.elementor-widget-divider{--divider-border-style:none;--divider-border-width:1px;--divider-color:#0c0d0e;--divider-icon-size:20px;--divider-element-spacing:10px;--divider-pattern-height:24px;--divider-pattern-size:20px;--divider-pattern-url:none;--divider-pattern-repeat:repeat-x}.elementor-widget-divider .elementor-divider{display:flex}.elementor-widget-divider .elementor-divider__text{font-size:15px;line-height:1;max-width:95%}.elementor-widget-divider .elementor-divider__element{margin:0 var(--divider-element-spacing);flex-shrink:0}.elementor-widget-divider .elementor-icon{font-size:var(--divider-icon-size)}.elementor-widget-divider .elementor-divider-separator{display:flex;margin:0;direction:ltr}.elementor-widget-divider--view-line_icon .elementor-divider-separator,.elementor-widget-divider--view-line_text .elementor-divider-separator{align-items:center}.elementor-widget-divider--view-line_icon .elementor-divider-separator:after,.elementor-widget-divider--view-line_icon .elementor-divider-separator:before,.elementor-widget-divider--view-line_text .elementor-divider-separator:after,.elementor-widget-divider--view-line_text .elementor-divider-separator:before{display:block;content:\"\";border-bottom:0;flex-grow:1;border-top:var(--divider-border-width) var(--divider-border-style) var(--divider-color)}.elementor-widget-divider--element-align-left .elementor-divider .elementor-divider-separator>.elementor-divider__svg:first-of-type{flex-grow:0;flex-shrink:100}.elementor-widget-divider--element-align-left .elementor-divider-separator:before{content:none}.elementor-widget-divider--element-align-left .elementor-divider__element{margin-left:0}.elementor-widget-divider--element-align-right .elementor-divider .elementor-divider-separator>.elementor-divider__svg:last-of-type{flex-grow:0;flex-shrink:100}.elementor-widget-divider--element-align-right .elementor-divider-separator:after{content:none}.elementor-widget-divider--element-align-right .elementor-divider__element{margin-right:0}.elementor-widget-divider:not(.elementor-widget-divider--view-line_text):not(.elementor-widget-divider--view-line_icon) .elementor-divider-separator{border-top:var(--divider-border-width) var(--divider-border-style) var(--divider-color)}.elementor-widget-divider--separator-type-pattern{--divider-border-style:none}.elementor-widget-divider--separator-type-pattern.elementor-widget-divider--view-line .elementor-divider-separator,.elementor-widget-divider--separator-type-pattern:not(.elementor-widget-divider--view-line) .elementor-divider-separator:after,.elementor-widget-divider--separator-type-pattern:not(.elementor-widget-divider--view-line) .elementor-divider-separator:before,.elementor-widget-divider--separator-type-pattern:not([class*=elementor-widget-divider--view]) .elementor-divider-separator{width:100%;min-height:var(--divider-pattern-height);-webkit-mask-size:var(--divider-pattern-size) 100%;mask-size:var(--divider-pattern-size) 100%;-webkit-mask-repeat:var(--divider-pattern-repeat);mask-repeat:var(--divider-pattern-repeat);background-color:var(--divider-color);-webkit-mask-image:var(--divider-pattern-url);mask-image:var(--divider-pattern-url)}.elementor-widget-divider--no-spacing{--divider-pattern-size:auto}.elementor-widget-divider--bg-round{--divider-pattern-repeat:round}.rtl .elementor-widget-divider .elementor-divider__text{direction:rtl}.e-con-inner>.elementor-widget-divider,.e-con>.elementor-widget-divider{width:var(--container-widget-width,100%);--flex-grow:var(--container-widget-flex-grow)}<\/style>\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-5b032d4 elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no\" data-id=\"5b032d4\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-b54e860\" data-id=\"b54e860\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-66c2b43 wpr-dual-heading-icon-top elementor-widget elementor-widget-wpr-dual-color-heading\" data-id=\"66c2b43\" data-element_type=\"widget\" data-widget_type=\"wpr-dual-color-heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t<div class=\"wpr-dual-heading-wrap\">\n\t\t\t\t<div class=\"wpr-dual-title-wrap\">\n\t\t\t\t\t<h5 class=\"wpr-dual-title\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"first\">Produk Digunakan<\/span>\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t<\/h5>\n\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<div class=\"wpr-dual-heading-description\" >Di sini kami memperkenalkan merek produk yang digunakan dalam proyek ini.<\/div>\n\t\t\t\t\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-de58cd3 elementor-position-left elementor-vertical-align-middle elementor-widget elementor-widget-image-box\" data-id=\"de58cd3\" data-element_type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<style>\/*! elementor - v3.18.0 - 20-12-2023 *\/\n.elementor-widget-image-box .elementor-image-box-content{width:100%}@media (min-width:768px){.elementor-widget-image-box.elementor-position-left .elementor-image-box-wrapper,.elementor-widget-image-box.elementor-position-right .elementor-image-box-wrapper{display:flex}.elementor-widget-image-box.elementor-position-right .elementor-image-box-wrapper{text-align:right;flex-direction:row-reverse}.elementor-widget-image-box.elementor-position-left .elementor-image-box-wrapper{text-align:left;flex-direction:row}.elementor-widget-image-box.elementor-position-top .elementor-image-box-img{margin:auto}.elementor-widget-image-box.elementor-vertical-align-top .elementor-image-box-wrapper{align-items:flex-start}.elementor-widget-image-box.elementor-vertical-align-middle .elementor-image-box-wrapper{align-items:center}.elementor-widget-image-box.elementor-vertical-align-bottom .elementor-image-box-wrapper{align-items:flex-end}}@media (max-width:767px){.elementor-widget-image-box .elementor-image-box-img{margin-left:auto!important;margin-right:auto!important;margin-bottom:15px}}.elementor-widget-image-box .elementor-image-box-img{display:inline-block}.elementor-widget-image-box .elementor-image-box-title a{color:inherit}.elementor-widget-image-box .elementor-image-box-wrapper{text-align:center}.elementor-widget-image-box .elementor-image-box-description{margin:0}<\/style><div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><a href=\"https:\/\/homelux.my.id\/homelux\/\" tabindex=\"-1\"><img decoding=\"async\" width=\"210\" height=\"63\" src=\"https:\/\/homelux.co.id\/wp-content\/uploads\/2023\/02\/logo-black-01.png\" class=\"attachment-large size-large wp-image-3090\" alt=\"\" \/><\/a><\/figure><div class=\"elementor-image-box-content\"><h6 class=\"elementor-image-box-title\"><a href=\"https:\/\/homelux.my.id\/homelux\/\">Homelux<\/a><\/h6><p class=\"elementor-image-box-description\">Produk Sistem Pintu &amp; Jendela dirancang dengan tingkat perhatian yang tinggi terhadap detail pada semua aspek, dan diproduksi secara presisi untuk memenuhi standar internasional, menghasilkan rangkaian produk yang luas dengan sifat estetika dan fungsional yang sangat baik.<\/p><\/div><\/div>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-5a06084 elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no\" data-id=\"5a06084\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-9e6b29f\" data-id=\"9e6b29f\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-0cf7bf2 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"0cf7bf2\" data-element_type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-aad0f10 elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no\" data-id=\"aad0f10\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-405a525\" data-id=\"405a525\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-0fae546 elementor-widget elementor-widget-eael-creative-button\" data-id=\"0fae546\" data-element_type=\"widget\" data-widget_type=\"eael-creative-button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t        <div class=\"eael-creative-button-wrapper\">\n\n            <a class=\"eael-creative-button eael-creative-button--default\" href=\"https:\/\/homelux.my.id\/graha-paramita-2-jakarta\/\" data-text=\"\">\n\n\t    \n                <div class=\"creative-button-inner\">\n\n                                            <span class=\"eael-creative-button-icon-left\"><i aria-hidden=\"true\" class=\"icon icon-previous-dark\"><\/i><\/span>                    \n                    <span class=\"cretive-button-text\">Bangunan Komersial Sebelumnya         <\/span>\n\n                                    <\/div>\n\t                        <\/a>\n        <\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-6b6eb0c\" data-id=\"6b6eb0c\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-cb67613 elementor-widget elementor-widget-eael-creative-button\" data-id=\"cb67613\" data-element_type=\"widget\" data-widget_type=\"eael-creative-button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t        <div class=\"eael-creative-button-wrapper\">\n\n            <a class=\"eael-creative-button eael-creative-button--default\" href=\"https:\/\/homelux.my.id\/project\/\" data-text=\"\">\n\n\t    \n                <div class=\"creative-button-inner\">\n\n                    \n                    <span class=\"cretive-button-text\">Project TOP        <\/span>\n\n                                    <\/div>\n\t                        <\/a>\n        <\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-2e7fa37\" data-id=\"2e7fa37\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-b670dd7 elementor-widget elementor-widget-eael-creative-button\" data-id=\"b670dd7\" data-element_type=\"widget\" data-widget_type=\"eael-creative-button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t        <div class=\"eael-creative-button-wrapper\">\n\n            <a class=\"eael-creative-button eael-creative-button--default\" href=\"#\" data-text=\"\">\n\n\t    \n                <div class=\"creative-button-inner\">\n\n                    \n                    <span class=\"cretive-button-text\">Gedung Komersial Selanjutnya            <\/span>\n\n                                            <span class=\"eael-creative-button-icon-right\"><i aria-hidden=\"true\" class=\"icon icon-next-dark\"><\/i><\/span>                                    <\/div>\n\t                        <\/a>\n        <\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>Aloft Hotel Bali Kuta PT. Indal Aluminium Industries Tbk. Commercial Building Welcome to the Aloft Bali Kuta Previous Next Bali Completed in 2022 1 Tower, 3 Floor &amp; 175 Room HOMELUX Product Product Used Here we introduce the product brand used in this project. Homelux Door &amp; Window System Products are designed with a high [&hellip;]<\/p>","protected":false},"author":1,"featured_media":0,"parent":3852,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_eb_attr":"","footnotes":""},"class_list":["post-3306","page","type-page","status-publish","hentry"],"blocksy_meta":{"styles_descriptor":{"styles":{"desktop":"","tablet":"","mobile":""},"google_fonts":[],"version":6}},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Aloft Hotel Bali Kuta using Best Product Sliding Door Homelux<\/title>\n<meta name=\"description\" content=\"Welcome to The Aloft Bali Kuta, Commercial Building One of our hi-rise projects in Bali using Homelux (PT. Indal Aluminium Industries Tbk.)\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/homelux.co.id\/id\/commercial-building-2\/aloft-bali-kuta\/\" \/>\n<meta property=\"og:locale\" content=\"id_ID\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Aloft Hotel Bali Kuta using Best Product Sliding Door Homelux\" \/>\n<meta property=\"og:description\" content=\"Welcome to The Aloft Bali Kuta, Commercial Building One of our hi-rise projects in Bali using Homelux (PT. Indal Aluminium Industries Tbk.)\" \/>\n<meta property=\"og:url\" content=\"https:\/\/homelux.co.id\/id\/commercial-building-2\/aloft-bali-kuta\/\" \/>\n<meta property=\"og:site_name\" content=\"Homelux\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/homelux.id\" \/>\n<meta property=\"article:modified_time\" content=\"2023-05-04T04:00:05+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/homelux.my.id\/wp-content\/uploads\/2023\/02\/1-14.jpg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Estimasi waktu membaca\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 menit\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/homelux.co.id\\\/commercial-building-2\\\/aloft-bali-kuta\\\/\",\"url\":\"https:\\\/\\\/homelux.co.id\\\/commercial-building-2\\\/aloft-bali-kuta\\\/\",\"name\":\"Aloft Hotel Bali Kuta using Best Product Sliding Door Homelux\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/homelux.co.id\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/homelux.co.id\\\/commercial-building-2\\\/aloft-bali-kuta\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/homelux.co.id\\\/commercial-building-2\\\/aloft-bali-kuta\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/homelux.my.id\\\/wp-content\\\/uploads\\\/2023\\\/02\\\/1-14.jpg\",\"datePublished\":\"2023-02-10T04:12:53+00:00\",\"dateModified\":\"2023-05-04T04:00:05+00:00\",\"description\":\"Welcome to The Aloft Bali Kuta, Commercial Building One of our hi-rise projects in Bali using Homelux (PT. Indal Aluminium Industries Tbk.)\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/homelux.co.id\\\/commercial-building-2\\\/aloft-bali-kuta\\\/#breadcrumb\"},\"inLanguage\":\"id\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/homelux.co.id\\\/commercial-building-2\\\/aloft-bali-kuta\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"id\",\"@id\":\"https:\\\/\\\/homelux.co.id\\\/commercial-building-2\\\/aloft-bali-kuta\\\/#primaryimage\",\"url\":\"https:\\\/\\\/homelux.my.id\\\/wp-content\\\/uploads\\\/2023\\\/02\\\/1-14.jpg\",\"contentUrl\":\"https:\\\/\\\/homelux.my.id\\\/wp-content\\\/uploads\\\/2023\\\/02\\\/1-14.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/homelux.co.id\\\/commercial-building-2\\\/aloft-bali-kuta\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/homelux.co.id\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Commercial Building\",\"item\":\"https:\\\/\\\/homelux.co.id\\\/commercial-building-2\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Aloft Bali Kuta\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/homelux.co.id\\\/#website\",\"url\":\"https:\\\/\\\/homelux.co.id\\\/\",\"name\":\"Homelux\",\"description\":\"Home Luxurious\",\"publisher\":{\"@id\":\"https:\\\/\\\/homelux.co.id\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/homelux.co.id\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"id\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/homelux.co.id\\\/#organization\",\"name\":\"Homelux\",\"url\":\"https:\\\/\\\/homelux.co.id\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"id\",\"@id\":\"https:\\\/\\\/homelux.co.id\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/homelux.co.id\\\/wp-content\\\/uploads\\\/2022\\\/12\\\/logo-black-01.png\",\"contentUrl\":\"https:\\\/\\\/homelux.co.id\\\/wp-content\\\/uploads\\\/2022\\\/12\\\/logo-black-01.png\",\"width\":210,\"height\":63,\"caption\":\"Homelux\"},\"image\":{\"@id\":\"https:\\\/\\\/homelux.co.id\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/homelux.id\",\"https:\\\/\\\/www.instagram.com\\\/homelux.indal\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/80267481\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Aloft Hotel Bali Kuta using Best Product Sliding Door Homelux","description":"Welcome to The Aloft Bali Kuta, Commercial Building One of our hi-rise projects in Bali using Homelux (PT. Indal Aluminium Industries Tbk.)","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/homelux.co.id\/id\/commercial-building-2\/aloft-bali-kuta\/","og_locale":"id_ID","og_type":"article","og_title":"Aloft Hotel Bali Kuta using Best Product Sliding Door Homelux","og_description":"Welcome to The Aloft Bali Kuta, Commercial Building One of our hi-rise projects in Bali using Homelux (PT. Indal Aluminium Industries Tbk.)","og_url":"https:\/\/homelux.co.id\/id\/commercial-building-2\/aloft-bali-kuta\/","og_site_name":"Homelux","article_publisher":"https:\/\/www.facebook.com\/homelux.id","article_modified_time":"2023-05-04T04:00:05+00:00","og_image":[{"url":"https:\/\/homelux.my.id\/wp-content\/uploads\/2023\/02\/1-14.jpg","type":"","width":"","height":""}],"twitter_card":"summary_large_image","twitter_misc":{"Estimasi waktu membaca":"2 menit"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/homelux.co.id\/commercial-building-2\/aloft-bali-kuta\/","url":"https:\/\/homelux.co.id\/commercial-building-2\/aloft-bali-kuta\/","name":"Aloft Hotel Bali Kuta using Best Product Sliding Door Homelux","isPartOf":{"@id":"https:\/\/homelux.co.id\/#website"},"primaryImageOfPage":{"@id":"https:\/\/homelux.co.id\/commercial-building-2\/aloft-bali-kuta\/#primaryimage"},"image":{"@id":"https:\/\/homelux.co.id\/commercial-building-2\/aloft-bali-kuta\/#primaryimage"},"thumbnailUrl":"https:\/\/homelux.my.id\/wp-content\/uploads\/2023\/02\/1-14.jpg","datePublished":"2023-02-10T04:12:53+00:00","dateModified":"2023-05-04T04:00:05+00:00","description":"Welcome to The Aloft Bali Kuta, Commercial Building One of our hi-rise projects in Bali using Homelux (PT. Indal Aluminium Industries Tbk.)","breadcrumb":{"@id":"https:\/\/homelux.co.id\/commercial-building-2\/aloft-bali-kuta\/#breadcrumb"},"inLanguage":"id","potentialAction":[{"@type":"ReadAction","target":["https:\/\/homelux.co.id\/commercial-building-2\/aloft-bali-kuta\/"]}]},{"@type":"ImageObject","inLanguage":"id","@id":"https:\/\/homelux.co.id\/commercial-building-2\/aloft-bali-kuta\/#primaryimage","url":"https:\/\/homelux.my.id\/wp-content\/uploads\/2023\/02\/1-14.jpg","contentUrl":"https:\/\/homelux.my.id\/wp-content\/uploads\/2023\/02\/1-14.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/homelux.co.id\/commercial-building-2\/aloft-bali-kuta\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/homelux.co.id\/"},{"@type":"ListItem","position":2,"name":"Commercial Building","item":"https:\/\/homelux.co.id\/commercial-building-2\/"},{"@type":"ListItem","position":3,"name":"Aloft Bali Kuta"}]},{"@type":"WebSite","@id":"https:\/\/homelux.co.id\/#website","url":"https:\/\/homelux.co.id\/","name":"Homelux","description":"Home Luxurious","publisher":{"@id":"https:\/\/homelux.co.id\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/homelux.co.id\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"id"},{"@type":"Organization","@id":"https:\/\/homelux.co.id\/#organization","name":"Homelux","url":"https:\/\/homelux.co.id\/","logo":{"@type":"ImageObject","inLanguage":"id","@id":"https:\/\/homelux.co.id\/#\/schema\/logo\/image\/","url":"https:\/\/homelux.co.id\/wp-content\/uploads\/2022\/12\/logo-black-01.png","contentUrl":"https:\/\/homelux.co.id\/wp-content\/uploads\/2022\/12\/logo-black-01.png","width":210,"height":63,"caption":"Homelux"},"image":{"@id":"https:\/\/homelux.co.id\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/homelux.id","https:\/\/www.instagram.com\/homelux.indal\/","https:\/\/www.linkedin.com\/company\/80267481"]}]}},"_links":{"self":[{"href":"https:\/\/homelux.co.id\/id\/wp-json\/wp\/v2\/pages\/3306","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/homelux.co.id\/id\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/homelux.co.id\/id\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/homelux.co.id\/id\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/homelux.co.id\/id\/wp-json\/wp\/v2\/comments?post=3306"}],"version-history":[{"count":14,"href":"https:\/\/homelux.co.id\/id\/wp-json\/wp\/v2\/pages\/3306\/revisions"}],"predecessor-version":[{"id":4004,"href":"https:\/\/homelux.co.id\/id\/wp-json\/wp\/v2\/pages\/3306\/revisions\/4004"}],"up":[{"embeddable":true,"href":"https:\/\/homelux.co.id\/id\/wp-json\/wp\/v2\/pages\/3852"}],"wp:attachment":[{"href":"https:\/\/homelux.co.id\/id\/wp-json\/wp\/v2\/media?parent=3306"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}