{"id":2419,"date":"2023-04-03T07:37:22","date_gmt":"2023-04-03T07:37:22","guid":{"rendered":"https:\/\/homelux.my.id\/?page_id=2419"},"modified":"2023-09-19T04:26:09","modified_gmt":"2023-09-19T04:26:09","slug":"sliding-doors-system","status":"publish","type":"page","link":"https:\/\/homelux.co.id\/id\/products\/sliding-doors-system\/","title":{"rendered":"homelux"},"content":{"rendered":"<div data-elementor-type=\"wp-page\" data-elementor-id=\"2419\" class=\"elementor elementor-2419\">\n\t\t\t\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-e04d1f9 elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no\" data-id=\"e04d1f9\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-ce5ec38\" data-id=\"ce5ec38\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-647f7cd wpr-pointer-none wpr-sub-icon-chevron-down wpr-mobile-menu-custom-width wpr-mobile-menu-drdown-align-left wpr-mobile-menu-item-align-left wpr-mobile-toggle-v5 wpr-main-menu-align-left wpr-main-menu-align--tabletleft wpr-main-menu-align--mobileleft wpr-sub-menu-fx-fade wpr-nav-menu-bp-mobile wpr-sub-divider-yes wpr-mobile-divider-yes elementor-widget elementor-widget-wpr-nav-menu\" data-id=\"647f7cd\" data-element_type=\"widget\" data-settings=\"{&quot;menu_layout&quot;:&quot;horizontal&quot;}\" data-widget_type=\"wpr-nav-menu.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<nav class=\"wpr-nav-menu-container wpr-nav-menu-horizontal\" data-trigger=\"click\"><ul id=\"menu-1-647f7cd\" class=\"wpr-nav-menu\"><li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-2694\"><a href=\"https:\/\/homelux.co.id\/id\/products\/folding-system\/\" class=\"wpr-menu-item wpr-pointer-item\">Folding System<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-2693\"><a href=\"https:\/\/homelux.co.id\/id\/products\/door-system\/\" class=\"wpr-menu-item wpr-pointer-item\">Door System<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-2692\"><a href=\"https:\/\/homelux.co.id\/id\/products\/window-system\/\" class=\"wpr-menu-item wpr-pointer-item\">Window System<\/a><\/li>\n<\/ul><\/nav><nav class=\"wpr-mobile-nav-menu-container\"><div class=\"wpr-mobile-toggle-wrap\"><div class=\"wpr-mobile-toggle\"><span class=\"wpr-mobile-toggle-line\"><\/span><span class=\"wpr-mobile-toggle-line\"><\/span><span class=\"wpr-mobile-toggle-line\"><\/span><\/div><\/div><ul id=\"mobile-menu-2-647f7cd\" class=\"wpr-mobile-nav-menu\"><li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-2694\"><a href=\"https:\/\/homelux.co.id\/id\/products\/folding-system\/\" class=\"wpr-mobile-menu-item\">Folding System<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-2693\"><a href=\"https:\/\/homelux.co.id\/id\/products\/door-system\/\" class=\"wpr-mobile-menu-item\">Door System<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-2692\"><a href=\"https:\/\/homelux.co.id\/id\/products\/window-system\/\" class=\"wpr-mobile-menu-item\">Window System<\/a><\/li>\n<\/ul><\/nav>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-ff24167 elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no\" data-id=\"ff24167\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-954ba23\" data-id=\"954ba23\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-e7c4c34 elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no\" data-id=\"e7c4c34\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-23b92d9\" data-id=\"23b92d9\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-cbfbea1 wpr-dual-heading-icon-top elementor-widget elementor-widget-wpr-dual-color-heading\" data-id=\"cbfbea1\" data-element_type=\"widget\" data-widget_type=\"wpr-dual-color-heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t<div class=\"wpr-dual-heading-wrap\">\n\t\t\t\t<div class=\"wpr-dual-title-wrap\">\n\t\t\t\t\t<h3 class=\"wpr-dual-title\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"first\">Sliding<\/span>\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"second\">System<\/span>\n\t\t\t\t\t\t\t\t\t\t<\/h3>\n\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<div class=\"wpr-dual-heading-description\" ><\/div>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<div class=\"wpr-dual-heading-icon-wrap\">\n\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" id=\"Layer_1\" x=\"0px\" y=\"0px\" viewbox=\"0 0 384 384\" style=\"enable-background:new 0 0 384 384;\" xml:space=\"preserve\"><g>\t<path d=\"M374.01,383.9c-121.26,0-242.53,0-363.79,0c-7.79-3.06-9.63-9.03-9.62-16.96C0.76,249.92,0.71,132.9,0.71,15.88  c0-11.06,4.04-15.11,15.1-15.11c116.99,0,233.98,0.05,350.97-0.11c7.92-0.01,13.91,1.79,16.95,9.62c0,121.29,0,242.59,0,363.88  C381.9,378.81,378.65,382.05,374.01,383.9z M371.67,371.92c0-120.03,0-239.61,0-359.32c-119.84,0-239.39,0-359.04,0  c0,119.92,0,239.59,0,359.32C132.44,371.92,251.91,371.92,371.67,371.92z\"><\/path>\t<path d=\"M192.11,18.7c52.89,0,105.77,0,158.66,0c10.45,0,14.82,4.34,14.82,14.73c0,105.92,0,211.85,0,317.77  c0,10.18-4.39,14.53-14.64,14.53c-105.9,0-211.8,0-317.7,0c-10.19,0-14.62-4.41-14.62-14.56c0-105.92,0-211.85,0-317.77  c0-10.44,4.3-14.71,14.82-14.71C86.34,18.7,139.23,18.7,192.11,18.7z M30.44,30.49c0,108.08,0,215.69,0,323.41  c52.03,0,103.82,0,155.61,0c0-107.97,0-215.66,0-323.41C134.05,30.49,82.35,30.49,30.44,30.49z M198.1,30.47  c0,108.07,0,215.67,0,323.43c52.01,0,103.8,0,155.64,0c0-107.96,0-215.65,0-323.43C301.75,30.47,250.04,30.47,198.1,30.47z\"><\/path>\t<path d=\"M170.62,123.33c1.95,2,4.38,4.49,6.44,6.59c-39.62,39.63-79.23,79.25-118.8,118.83c-1.83-1.93-4.26-4.51-6.33-6.69  C91.07,202.9,130.68,163.28,170.62,123.33z\"><\/path>\t<path d=\"M36.64,195.19c0-8.35-0.03-16.7,0.01-25.05c0.03-6.27,3.25-8.67,9.09-6.77c5.08,1.65,10.12,3.44,15.22,5.06  c3.58,1.14,5.21,3.44,5.19,7.2c-0.06,13.08-0.06,26.17,0,39.26c0.01,3.77-1.69,6.03-5.26,7.15c-5.22,1.64-10.37,3.48-15.58,5.15  c-5.19,1.67-8.59-0.74-8.64-6.2C36.59,212.38,36.65,203.79,36.64,195.19z M48.46,213.62c6.1-0.83,6.11-0.83,6.11-6.25  c0-8.1,0-16.2,0-24.3c0-5.42,0-5.42-6.11-6.26C48.46,189.09,48.46,201.34,48.46,213.62z\"><\/path>\t<path d=\"M82.11,189.43c-2.16-2.26-4.62-4.85-6.83-7.17c23.6-23.6,47.26-47.27,71.1-71.11c2.14,2.27,4.6,4.86,6.81,7.19  C129.63,141.91,105.96,165.58,82.11,189.43z\"><\/path>\t<path d=\"M140.7,189.23c1.92,1.97,4.35,4.47,6.4,6.58c-21.65,21.65-43.29,43.29-64.89,64.89c-1.81-1.92-4.24-4.49-6.34-6.72  C97.04,232.83,118.69,211.21,140.7,189.23z\"><\/path>\t<path d=\"M325.91,123.16c2.3,2.27,4.84,4.78,7.13,7.04c-39.76,39.77-79.39,79.41-119.08,119.11c-2.32-2.26-4.87-4.76-7.16-7  C246.6,202.49,286.22,162.86,325.91,123.16z\"><\/path>\t<path d=\"M347.58,195.51c0,8.35,0.04,16.7-0.01,25.05c-0.03,5.95-3.37,8.37-8.97,6.55c-5.2-1.69-10.37-3.49-15.57-5.19  c-3.42-1.12-4.96-3.4-4.95-6.99c0.05-13.21,0.04-26.42,0.01-39.63c-0.01-3.43,1.53-5.66,4.78-6.73c5.43-1.79,10.84-3.65,16.29-5.37  c4.96-1.57,8.34,0.86,8.39,6.14C347.65,178.06,347.58,186.79,347.58,195.51z M335.69,213.7c0-12.45,0-24.68,0-36.96  c-6.02,1.17-6.02,1.17-6.03,6.5c0,7.97,0,15.95,0,23.92C329.66,212.51,329.67,212.51,335.69,213.7z\"><\/path>\t<path d=\"M237.6,189.32c-2.08-2.1-4.52-4.56-6.63-6.68c23.74-23.73,47.39-47.37,71.07-71.05c1.87,2.01,4.29,4.61,6.38,6.86  C285.19,141.7,261.55,165.36,237.6,189.32z\"><\/path>\t<path d=\"M238,261.14c-2.34-2.22-4.94-4.67-7.32-6.93c21.79-21.79,43.37-43.38,64.92-64.93c2.19,2.36,4.66,5.03,6.87,7.4  C281.25,217.9,259.58,239.56,238,261.14z\"><\/path><\/g><\/svg>\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f680ed6 elementor-widget elementor-widget-text-editor\" data-id=\"f680ed6\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<style>\/*! elementor - v3.18.0 - 20-12-2023 *\/\n.elementor-widget-text-editor.elementor-drop-cap-view-stacked .elementor-drop-cap{background-color:#69727d;color:#fff}.elementor-widget-text-editor.elementor-drop-cap-view-framed .elementor-drop-cap{color:#69727d;border:3px solid;background-color:transparent}.elementor-widget-text-editor:not(.elementor-drop-cap-view-default) .elementor-drop-cap{margin-top:8px}.elementor-widget-text-editor:not(.elementor-drop-cap-view-default) .elementor-drop-cap-letter{width:1em;height:1em}.elementor-widget-text-editor .elementor-drop-cap{float:left;text-align:center;line-height:1;font-size:50px}.elementor-widget-text-editor .elementor-drop-cap-letter{display:inline-block}<\/style>\t\t\t\t<p>Sliding doors from Homelux offer a wide range of new design concepts for use indoors. Who wouldn&#8217;t want to extend their office or living space at the turn of a handle?\u00a0 Both system constructions can be combined seamlessly thanks to their design.\u00a0<span style=\"color: var(--theme-text-color); font-family: var(--fontFamily); font-size: inherit; font-style: var(--fontStyle, inherit); font-weight: var(--fontWeight); letter-spacing: var(--letterSpacing); text-align: inherit; text-transform: var(--textTransform);\">Homelux allows you to combine the form, function, colour and technology of your sliding doors as desired. Sliding doors offer perfect functionality and the various opening options open up special design possibilities. The opening types on offer in the sliding and lift-and-slide doors depend on the system.<\/span><\/p><p>Sliding door offers a lot of benefits such as letting natural light in, great airflow and circulation, easy operation, space maximization, and a better view.\u00a0<span style=\"color: var(--theme-text-color); font-family: var(--fontFamily); font-size: inherit; font-style: var(--fontStyle, inherit); font-weight: var(--fontWeight); letter-spacing: var(--letterSpacing); text-align: inherit; text-transform: var(--textTransform);\">Homelux Sliding Door is manufactured with best technology, and gradually being improved and advanced. With slim and round profiles, Wide View Sliding fulfills the functional needs of the most comfortable living space.<\/span><\/p><p>Aluminium is the right choice for you. Our sliding doors meet the highest quality requirements and offer numerous benefits<\/p><div>\u00a0<\/div>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-a657f5b elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no\" data-id=\"a657f5b\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-582a632\" data-id=\"582a632\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5c10366 wpr-grid-columns-3 wpr-grid-columns--tablet2 wpr-grid-columns--mobile1 wpr-grid-pagination-center wpr-item-styles-inner elementor-widget elementor-widget-wpr-woo-grid\" data-id=\"5c10366\" data-element_type=\"widget\" data-widget_type=\"wpr-woo-grid.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<ul class=\"wpr-grid-filters elementor-clearfix wpr-grid-filters-sep-right\"><li class=\"wpr-pointer-none wpr-pointer-line-fx wpr-pointer-fx-none\"><span data-filter=\"*\" class=\"wpr-active-filter\">All<\/span><em class=\"wpr-grid-filters-sep\"><\/em><\/li><ul data-parent=\".product_cat-homelux\" class=\"wpr-sub-filters\"><li data-role=\"back\" class=\"wpr-pointer-none wpr-pointer-line-fx wpr-pointer-fx-none\"><span class=\"wpr-back-filter\" data-filter=\".product_cat-homelux\"><i class=\"fas fa-long-arrow-alt-left\"><\/i>&nbsp;&nbsp;Back<\/span><\/li><li data-role=\"sub\" class=\"wpr-pointer-none wpr-pointer-line-fx wpr-pointer-fx-none\"><span  data-filter=\".product_cat-folding-system\">Folding System<\/span><em class=\"wpr-grid-filters-sep\"><\/em><\/li><li data-role=\"sub\" class=\"wpr-pointer-none wpr-pointer-line-fx wpr-pointer-fx-none\"><span  data-filter=\".product_cat-window-system\">Window System<\/span><em class=\"wpr-grid-filters-sep\"><\/em><\/li><li data-role=\"sub\" class=\"wpr-pointer-none wpr-pointer-line-fx wpr-pointer-fx-none\"><span  data-filter=\".product_cat-sliding-system\">Sliding System<\/span><em class=\"wpr-grid-filters-sep\"><\/em><\/li><li data-role=\"sub\" class=\"wpr-pointer-none wpr-pointer-line-fx wpr-pointer-fx-none\"><span  data-filter=\".product_cat-door-system\">Door System<\/span><em class=\"wpr-grid-filters-sep\"><\/em><\/li><li data-role=\"sub\" class=\"wpr-pointer-none wpr-pointer-line-fx wpr-pointer-fx-none\"><span  data-filter=\".product_cat-door-system-homelux\">Door System<\/span><em class=\"wpr-grid-filters-sep\"><\/em><\/li><\/ul><\/ul><section class=\"wpr-grid elementor-clearfix\" data-settings=\"{&quot;layout&quot;:&quot;fitRows&quot;,&quot;stick_last_element_to_bottom&quot;:&quot;&quot;,&quot;columns_desktop&quot;:&quot;3&quot;,&quot;gutter_hr&quot;:20,&quot;gutter_hr_mobile&quot;:20,&quot;gutter_hr_mobile_extra&quot;:20,&quot;gutter_hr_tablet&quot;:20,&quot;gutter_hr_tablet_extra&quot;:20,&quot;gutter_hr_laptop&quot;:20,&quot;gutter_hr_widescreen&quot;:20,&quot;gutter_vr&quot;:57,&quot;gutter_vr_mobile&quot;:57,&quot;gutter_vr_mobile_extra&quot;:57,&quot;gutter_vr_tablet&quot;:57,&quot;gutter_vr_tablet_extra&quot;:57,&quot;gutter_vr_laptop&quot;:57,&quot;gutter_vr_widescreen&quot;:57,&quot;animation&quot;:&quot;default&quot;,&quot;animation_duration&quot;:0.3,&quot;animation_delay&quot;:0.1,&quot;deeplinking&quot;:&quot;&quot;,&quot;filters_linkable&quot;:&quot;no&quot;,&quot;filters_default_filter&quot;:&quot;&quot;,&quot;filters_count&quot;:&quot;&quot;,&quot;filters_hide_empty&quot;:&quot;no&quot;,&quot;filters_animation&quot;:&quot;default&quot;,&quot;filters_animation_duration&quot;:0.3,&quot;filters_animation_delay&quot;:0.1,&quot;pagination_type&quot;:&quot;load-more&quot;,&quot;pagination_max_pages&quot;:1,&quot;lightbox&quot;:{&quot;selector&quot;:&quot;.wpr-grid-image-wrap&quot;,&quot;iframeMaxWidth&quot;:&quot;60%&quot;,&quot;hash&quot;:false,&quot;autoplay&quot;:&quot;true&quot;,&quot;pause&quot;:5000,&quot;progressBar&quot;:&quot;true&quot;,&quot;counter&quot;:&quot;true&quot;,&quot;controls&quot;:&quot;true&quot;,&quot;getCaptionFromTitleOrAlt&quot;:&quot;true&quot;,&quot;thumbnail&quot;:&quot;&quot;,&quot;showThumbByDefault&quot;:&quot;&quot;,&quot;share&quot;:&quot;&quot;,&quot;zoom&quot;:&quot;true&quot;,&quot;fullScreen&quot;:&quot;true&quot;,&quot;download&quot;:&quot;true&quot;}}\" data-found-posts = \"8\"><article class=\"wpr-grid-item elementor-clearfix post-1639 product type-product status-publish has-post-thumbnail product_cat-sliding-system first instock shipping-taxable product-type-simple\"><div class=\"wpr-grid-item-inner\"><div class=\"wpr-grid-media-wrap wpr-effect-size-medium\" data-overlay-link=\"yes\"><div class=\"wpr-grid-image-wrap\" data-src=\"https:\/\/homelux.co.id\/wp-content\/uploads\/2022\/12\/8.-SLIM-SLIDING-WINDOW.jpg\"  data-img-on-hover=\"\" data-src-secondary=\"\"><img decoding=\"async\" src=\"https:\/\/homelux.co.id\/wp-content\/uploads\/2022\/12\/8.-SLIM-SLIDING-WINDOW.jpg\" alt=\"Sash height up to 1800 mm.Sash width up to 2000 mm.Panoramic field or view and increase natural lighting.Flush handle with cylinder lock.Flush handle.Slim series system with low sash width allows for panoramic views when closed.Cylinder and handle flushed with frame for a sleek, modern appearance.\" class=\"wpr-anim-timing-ease-default\"><\/div><div class=\"wpr-grid-media-hover wpr-animation-wrap\"><div class=\"wpr-grid-media-hover-bg  wpr-overlay-fade-in wpr-anim-size-large wpr-anim-timing-ease-default wpr-anim-transparency\" data-url=\"https:\/\/homelux.co.id\/id\/product\/slim-sliding-window-psw50\/\"><\/div><div class=\"wpr-cv-container\"><div class=\"wpr-cv-outer\"><div class=\"wpr-cv-inner\"><div class=\"wpr-grid-media-hover-middle elementor-clearfix\"><div class=\"wpr-grid-item-status elementor-repeater-item-534bd1c wpr-grid-item-display-block wpr-grid-item-align-middle wpr-element-fade-in wpr-anim-size-large wpr-anim-timing-ease-default wpr-anim-transparency\"><div class=\"inner-block\"><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><div class=\"wpr-grid-item-below-content elementor-clearfix\"><span class=\"wpr-grid-item-title elementor-repeater-item-fcc88d8 wpr-grid-item-display-block wpr-grid-item-align-center wpr-pointer-none wpr-pointer-line-fx wpr-pointer-fx-fade\"><div class=\"inner-block\"><a target=\"_self\"   href=\"https:\/\/homelux.co.id\/id\/product\/slim-sliding-window-psw50\/\">Slim Sliding Window | PSW50<\/a><\/div><\/span><div class=\"wpr-grid-item-price elementor-repeater-item-2daea4e wpr-grid-item-display-block wpr-grid-item-align-left\"><div class=\"inner-block\"><span><\/span><\/div><\/div><\/div><\/div><\/article><article class=\"wpr-grid-item elementor-clearfix post-1637 product type-product status-publish has-post-thumbnail product_cat-sliding-system  instock shipping-taxable product-type-simple\"><div class=\"wpr-grid-item-inner\"><div class=\"wpr-grid-media-wrap wpr-effect-size-medium\" data-overlay-link=\"yes\"><div class=\"wpr-grid-image-wrap\" data-src=\"https:\/\/homelux.co.id\/wp-content\/uploads\/2022\/12\/7.-LIFT-AND-SLIDE-DOOR.jpg\"  data-img-on-hover=\"\" data-src-secondary=\"\"><img decoding=\"async\" src=\"https:\/\/homelux.co.id\/wp-content\/uploads\/2022\/12\/7.-LIFT-AND-SLIDE-DOOR.jpg\" alt=\"Sash height up to 3000 mm.Sash width up to 3000 mm.Fitting with 4 wheel carriages makes easy to open the door.Flexible glass :single and double glass.Locking SystemQuad rollers for easier operation.Lift and Slide system for improved thermal, acoustic and weather insulation.Door may be locked in place at any point along the rail.Able to accommodate 24 mm glass.\" class=\"wpr-anim-timing-ease-default\"><\/div><div class=\"wpr-grid-media-hover wpr-animation-wrap\"><div class=\"wpr-grid-media-hover-bg  wpr-overlay-fade-in wpr-anim-size-large wpr-anim-timing-ease-default wpr-anim-transparency\" data-url=\"https:\/\/homelux.co.id\/id\/product\/lift-and-slide-door-ls50\/\"><\/div><div class=\"wpr-cv-container\"><div class=\"wpr-cv-outer\"><div class=\"wpr-cv-inner\"><div class=\"wpr-grid-media-hover-middle elementor-clearfix\"><div class=\"wpr-grid-item-status elementor-repeater-item-534bd1c wpr-grid-item-display-block wpr-grid-item-align-middle wpr-element-fade-in wpr-anim-size-large wpr-anim-timing-ease-default wpr-anim-transparency\"><div class=\"inner-block\"><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><div class=\"wpr-grid-item-below-content elementor-clearfix\"><span class=\"wpr-grid-item-title elementor-repeater-item-fcc88d8 wpr-grid-item-display-block wpr-grid-item-align-center wpr-pointer-none wpr-pointer-line-fx wpr-pointer-fx-fade\"><div class=\"inner-block\"><a target=\"_self\"   href=\"https:\/\/homelux.co.id\/id\/product\/lift-and-slide-door-ls50\/\">Lift And Slide Door | LS50<\/a><\/div><\/span><div class=\"wpr-grid-item-price elementor-repeater-item-2daea4e wpr-grid-item-display-block wpr-grid-item-align-left\"><div class=\"inner-block\"><span><\/span><\/div><\/div><\/div><\/div><\/article><article class=\"wpr-grid-item elementor-clearfix post-1635 product type-product status-publish has-post-thumbnail product_cat-sliding-system last instock shipping-taxable product-type-simple\"><div class=\"wpr-grid-item-inner\"><div class=\"wpr-grid-media-wrap wpr-effect-size-medium\" data-overlay-link=\"yes\"><div class=\"wpr-grid-image-wrap\" data-src=\"https:\/\/homelux.co.id\/wp-content\/uploads\/2022\/12\/6.-SLIDING-DOOR-wiht-Mosquito-Screen.jpg\"  data-img-on-hover=\"\" data-src-secondary=\"\"><img decoding=\"async\" src=\"https:\/\/homelux.co.id\/wp-content\/uploads\/2022\/12\/6.-SLIDING-DOOR-wiht-Mosquito-Screen.jpg\" alt=\"Sash height up to 3000 mm.Sash width up to 1000 mm.Mosquito screen :Stainless steel,Aluminium.Frame depth 159 mm.Flush track is available.Screen sash and glass door handleLightweight design for easier operation.Durable stainless steel\/ aluminum mosquito screen for security against insects, creatures.Flush track system option available.Multiple customization options for sliding handle.Both sets of doors can be opened for flexibility.Able to accommodate 24 mm glass.\" class=\"wpr-anim-timing-ease-default\"><\/div><div class=\"wpr-grid-media-hover wpr-animation-wrap\"><div class=\"wpr-grid-media-hover-bg  wpr-overlay-fade-in wpr-anim-size-large wpr-anim-timing-ease-default wpr-anim-transparency\" data-url=\"https:\/\/homelux.co.id\/id\/product\/sliding-door-with-mosquito-screen-sd40m\/\"><\/div><div class=\"wpr-cv-container\"><div class=\"wpr-cv-outer\"><div class=\"wpr-cv-inner\"><div class=\"wpr-grid-media-hover-middle elementor-clearfix\"><div class=\"wpr-grid-item-status elementor-repeater-item-534bd1c wpr-grid-item-display-block wpr-grid-item-align-middle wpr-element-fade-in wpr-anim-size-large wpr-anim-timing-ease-default wpr-anim-transparency\"><div class=\"inner-block\"><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><div class=\"wpr-grid-item-below-content elementor-clearfix\"><span class=\"wpr-grid-item-title elementor-repeater-item-fcc88d8 wpr-grid-item-display-block wpr-grid-item-align-center wpr-pointer-none wpr-pointer-line-fx wpr-pointer-fx-fade\"><div class=\"inner-block\"><a target=\"_self\"   href=\"https:\/\/homelux.co.id\/id\/product\/sliding-door-with-mosquito-screen-sd40m\/\">Sliding Door with Mosquito Screen | SD40M<\/a><\/div><\/span><div class=\"wpr-grid-item-price elementor-repeater-item-2daea4e wpr-grid-item-display-block wpr-grid-item-align-left\"><div class=\"inner-block\"><span><\/span><\/div><\/div><\/div><\/div><\/article><article class=\"wpr-grid-item elementor-clearfix post-1633 product type-product status-publish has-post-thumbnail product_cat-sliding-system first instock shipping-taxable product-type-simple\"><div class=\"wpr-grid-item-inner\"><div class=\"wpr-grid-media-wrap wpr-effect-size-medium\" data-overlay-link=\"yes\"><div class=\"wpr-grid-image-wrap\" data-src=\"https:\/\/homelux.co.id\/wp-content\/uploads\/2022\/12\/5.-SLIDING-DOOR-Flush-Track.jpg\"  data-img-on-hover=\"\" data-src-secondary=\"\"><img decoding=\"async\" src=\"https:\/\/homelux.co.id\/wp-content\/uploads\/2022\/12\/5.-SLIDING-DOOR-Flush-Track.jpg\" alt=\"Sash height up to 3000 mm.Sash width up to 1500 mm.Flush track.Frame depth 106 mm.Common TrackFlush TrackLightweight design for easier operation.Flush track system \u2013 ideal for indoor use.Multiple customization options for sliding handle.Both doors can be opened for flexibility.Able to accommodate 24 mm glass.\" class=\"wpr-anim-timing-ease-default\"><\/div><div class=\"wpr-grid-media-hover wpr-animation-wrap\"><div class=\"wpr-grid-media-hover-bg  wpr-overlay-fade-in wpr-anim-size-large wpr-anim-timing-ease-default wpr-anim-transparency\" data-url=\"https:\/\/homelux.co.id\/id\/product\/sliding-door-flush-track-sd40\/\"><\/div><div class=\"wpr-cv-container\"><div class=\"wpr-cv-outer\"><div class=\"wpr-cv-inner\"><div class=\"wpr-grid-media-hover-middle elementor-clearfix\"><div class=\"wpr-grid-item-status elementor-repeater-item-534bd1c wpr-grid-item-display-block wpr-grid-item-align-middle wpr-element-fade-in wpr-anim-size-large wpr-anim-timing-ease-default wpr-anim-transparency\"><div class=\"inner-block\"><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><div class=\"wpr-grid-item-below-content elementor-clearfix\"><span class=\"wpr-grid-item-title elementor-repeater-item-fcc88d8 wpr-grid-item-display-block wpr-grid-item-align-center wpr-pointer-none wpr-pointer-line-fx wpr-pointer-fx-fade\"><div class=\"inner-block\"><a target=\"_self\"   href=\"https:\/\/homelux.co.id\/id\/product\/sliding-door-flush-track-sd40\/\">Sliding Door Flush Track | SD40<\/a><\/div><\/span><div class=\"wpr-grid-item-price elementor-repeater-item-2daea4e wpr-grid-item-display-block wpr-grid-item-align-left\"><div class=\"inner-block\"><span><\/span><\/div><\/div><\/div><\/div><\/article><article class=\"wpr-grid-item elementor-clearfix post-1631 product type-product status-publish has-post-thumbnail product_cat-sliding-system  instock shipping-taxable product-type-simple\"><div class=\"wpr-grid-item-inner\"><div class=\"wpr-grid-media-wrap wpr-effect-size-medium\" data-overlay-link=\"yes\"><div class=\"wpr-grid-image-wrap\" data-src=\"https:\/\/homelux.co.id\/wp-content\/uploads\/2022\/12\/4.-Sliding-Door-SD40-70.jpg\"  data-img-on-hover=\"\" data-src-secondary=\"\"><img decoding=\"async\" src=\"https:\/\/homelux.co.id\/wp-content\/uploads\/2022\/12\/4.-Sliding-Door-SD40-70.jpg\" alt=\"Sash height up to 3000 mm.Sash width up to 1000 mm.Flexible glass :single and double glass.Frame depth 106 mm.Top TrackBottom TrackLever HandleSliding HandleLightweight design with top and bottom tracks for easier operation.Multiple customization options for sliding handle.Both doors can be opened for flexibility.Able to accommodate 24 mm glass.\" class=\"wpr-anim-timing-ease-default\"><\/div><div class=\"wpr-grid-media-hover wpr-animation-wrap\"><div class=\"wpr-grid-media-hover-bg  wpr-overlay-fade-in wpr-anim-size-large wpr-anim-timing-ease-default wpr-anim-transparency\" data-url=\"https:\/\/homelux.co.id\/id\/product\/slim-lift-slide-door-plsd60-copy\/\"><\/div><div class=\"wpr-cv-container\"><div class=\"wpr-cv-outer\"><div class=\"wpr-cv-inner\"><div class=\"wpr-grid-media-hover-middle elementor-clearfix\"><div class=\"wpr-grid-item-status elementor-repeater-item-534bd1c wpr-grid-item-display-block wpr-grid-item-align-middle wpr-element-fade-in wpr-anim-size-large wpr-anim-timing-ease-default wpr-anim-transparency\"><div class=\"inner-block\"><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><div class=\"wpr-grid-item-below-content elementor-clearfix\"><span class=\"wpr-grid-item-title elementor-repeater-item-fcc88d8 wpr-grid-item-display-block wpr-grid-item-align-center wpr-pointer-none wpr-pointer-line-fx wpr-pointer-fx-fade\"><div class=\"inner-block\"><a target=\"_self\"   href=\"https:\/\/homelux.co.id\/id\/product\/slim-lift-slide-door-plsd60-copy\/\">Sliding Door | SD40-70<\/a><\/div><\/span><div class=\"wpr-grid-item-price elementor-repeater-item-2daea4e wpr-grid-item-display-block wpr-grid-item-align-left\"><div class=\"inner-block\"><span><\/span><\/div><\/div><\/div><\/div><\/article><article class=\"wpr-grid-item elementor-clearfix post-596 product type-product status-publish has-post-thumbnail product_cat-sliding-system last instock shipping-taxable product-type-simple\"><div class=\"wpr-grid-item-inner\"><div class=\"wpr-grid-media-wrap wpr-effect-size-medium\" data-overlay-link=\"yes\"><div class=\"wpr-grid-image-wrap\" data-src=\"https:\/\/homelux.co.id\/wp-content\/uploads\/2021\/04\/2.-SLIM-SLIDING-DOOR.jpg\"  data-img-on-hover=\"\" data-src-secondary=\"\"><img decoding=\"async\" src=\"https:\/\/homelux.co.id\/wp-content\/uploads\/2021\/04\/2.-SLIM-SLIDING-DOOR.jpg\" alt=\"Slim Sliding Door Frameless Corner | PSD50\" class=\"wpr-anim-timing-ease-default\"><\/div><div class=\"wpr-grid-media-hover wpr-animation-wrap\"><div class=\"wpr-grid-media-hover-bg  wpr-overlay-fade-in wpr-anim-size-large wpr-anim-timing-ease-default wpr-anim-transparency\" data-url=\"https:\/\/homelux.co.id\/id\/product\/slim-sliding-door-frameless-corner\/\"><\/div><div class=\"wpr-cv-container\"><div class=\"wpr-cv-outer\"><div class=\"wpr-cv-inner\"><div class=\"wpr-grid-media-hover-middle elementor-clearfix\"><div class=\"wpr-grid-item-status elementor-repeater-item-534bd1c wpr-grid-item-display-block wpr-grid-item-align-middle wpr-element-fade-in wpr-anim-size-large wpr-anim-timing-ease-default wpr-anim-transparency\"><div class=\"inner-block\"><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><div class=\"wpr-grid-item-below-content elementor-clearfix\"><span class=\"wpr-grid-item-title elementor-repeater-item-fcc88d8 wpr-grid-item-display-block wpr-grid-item-align-center wpr-pointer-none wpr-pointer-line-fx wpr-pointer-fx-fade\"><div class=\"inner-block\"><a target=\"_self\"   href=\"https:\/\/homelux.co.id\/id\/product\/slim-sliding-door-frameless-corner\/\">Slim Sliding Door Frameless Corner | PSD50<\/a><\/div><\/span><div class=\"wpr-grid-item-price elementor-repeater-item-2daea4e wpr-grid-item-display-block wpr-grid-item-align-left\"><div class=\"inner-block\"><span><\/span><\/div><\/div><\/div><\/div><\/article><article class=\"wpr-grid-item elementor-clearfix post-579 product type-product status-publish has-post-thumbnail product_cat-sliding-system first instock shipping-taxable product-type-simple\"><div class=\"wpr-grid-item-inner\"><div class=\"wpr-grid-media-wrap wpr-effect-size-medium\" data-overlay-link=\"yes\"><div class=\"wpr-grid-image-wrap\" data-src=\"https:\/\/homelux.co.id\/wp-content\/uploads\/2021\/04\/1.-AIRTIGHT-2.jpg\"  data-img-on-hover=\"\" data-src-secondary=\"\"><img decoding=\"async\" src=\"https:\/\/homelux.co.id\/wp-content\/uploads\/2021\/04\/1.-AIRTIGHT-2.jpg\" alt=\"Slide &amp; Sealed Door Frameless Corner\" class=\"wpr-anim-timing-ease-default\"><\/div><div class=\"wpr-grid-media-hover wpr-animation-wrap\"><div class=\"wpr-grid-media-hover-bg  wpr-overlay-fade-in wpr-anim-size-large wpr-anim-timing-ease-default wpr-anim-transparency\" data-url=\"https:\/\/homelux.co.id\/id\/product\/airtight-sliding-door\/\"><\/div><div class=\"wpr-cv-container\"><div class=\"wpr-cv-outer\"><div class=\"wpr-cv-inner\"><div class=\"wpr-grid-media-hover-middle elementor-clearfix\"><div class=\"wpr-grid-item-status elementor-repeater-item-534bd1c wpr-grid-item-display-block wpr-grid-item-align-middle wpr-element-fade-in wpr-anim-size-large wpr-anim-timing-ease-default wpr-anim-transparency\"><div class=\"inner-block\"><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><div class=\"wpr-grid-item-below-content elementor-clearfix\"><span class=\"wpr-grid-item-title elementor-repeater-item-fcc88d8 wpr-grid-item-display-block wpr-grid-item-align-center wpr-pointer-none wpr-pointer-line-fx wpr-pointer-fx-fade\"><div class=\"inner-block\"><a target=\"_self\"   href=\"https:\/\/homelux.co.id\/id\/product\/airtight-sliding-door\/\">AIRTIGHT SLIDING DOOR | PSSD60<\/a><\/div><\/span><div class=\"wpr-grid-item-price elementor-repeater-item-2daea4e wpr-grid-item-display-block wpr-grid-item-align-left\"><div class=\"inner-block\"><span><\/span><\/div><\/div><\/div><\/div><\/article><article class=\"wpr-grid-item elementor-clearfix post-577 product type-product status-publish has-post-thumbnail product_cat-sliding-system  instock shipping-taxable product-type-simple\"><div class=\"wpr-grid-item-inner\"><div class=\"wpr-grid-media-wrap wpr-effect-size-medium\" data-overlay-link=\"yes\"><div class=\"wpr-grid-image-wrap\" data-src=\"https:\/\/homelux.co.id\/wp-content\/uploads\/2021\/04\/3.-SLIM-LIFT-SLIDE-DOOR.jpg\"  data-img-on-hover=\"\" data-src-secondary=\"\"><img decoding=\"async\" src=\"https:\/\/homelux.co.id\/wp-content\/uploads\/2021\/04\/3.-SLIM-LIFT-SLIDE-DOOR.jpg\" alt=\"Slim series system with low sash width allows for panoramic views when closed.Lift and Slide system for improved thermal, acoustic and weather insulation.Door may be locked in place at any point along the rail.\" class=\"wpr-anim-timing-ease-default\"><\/div><div class=\"wpr-grid-media-hover wpr-animation-wrap\"><div class=\"wpr-grid-media-hover-bg  wpr-overlay-fade-in wpr-anim-size-large wpr-anim-timing-ease-default wpr-anim-transparency\" data-url=\"https:\/\/homelux.co.id\/id\/product\/wooden-table\/\"><\/div><div class=\"wpr-cv-container\"><div class=\"wpr-cv-outer\"><div class=\"wpr-cv-inner\"><div class=\"wpr-grid-media-hover-middle elementor-clearfix\"><div class=\"wpr-grid-item-status elementor-repeater-item-534bd1c wpr-grid-item-display-block wpr-grid-item-align-middle wpr-element-fade-in wpr-anim-size-large wpr-anim-timing-ease-default wpr-anim-transparency\"><div class=\"inner-block\"><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><div class=\"wpr-grid-item-below-content elementor-clearfix\"><span class=\"wpr-grid-item-title elementor-repeater-item-fcc88d8 wpr-grid-item-display-block wpr-grid-item-align-center wpr-pointer-none wpr-pointer-line-fx wpr-pointer-fx-fade\"><div class=\"inner-block\"><a target=\"_self\"   href=\"https:\/\/homelux.co.id\/id\/product\/wooden-table\/\">Slim Lift &#038; Slide Door | PLSD60<\/a><\/div><\/span><div class=\"wpr-grid-item-price elementor-repeater-item-2daea4e wpr-grid-item-display-block wpr-grid-item-align-left\"><div class=\"inner-block\"><span><\/span><\/div><\/div><\/div><\/div><\/article><\/section>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>Folding System Door System Window System Folding System Door System Window System Sliding System Sliding doors from Homelux offer a wide range of new design concepts for use indoors. Who wouldn&#8217;t want to extend their office or living space at the turn of a handle?\u00a0 Both system constructions can be combined seamlessly thanks to their [&hellip;]<\/p>","protected":false},"author":1,"featured_media":0,"parent":2460,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_eb_attr":"","footnotes":""},"class_list":["post-2419","page","type-page","status-publish","hentry"],"blocksy_meta":{"styles_descriptor":{"styles":{"desktop":"","tablet":"","mobile":""},"google_fonts":[],"version":6}},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Sliding doors from Homelux<\/title>\n<meta name=\"description\" content=\"Sliding doors from Homelux offer a wide range of new design concepts for use indoors Homelux allows you to combine the form, function &amp; colour\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/homelux.co.id\/id\/products\/sliding-doors-system\/\" \/>\n<meta property=\"og:locale\" content=\"id_ID\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Sliding doors from Homelux\" \/>\n<meta property=\"og:description\" content=\"Sliding doors from Homelux offer a wide range of new design concepts for use indoors Homelux allows you to combine the form, function &amp; colour\" \/>\n<meta property=\"og:url\" content=\"https:\/\/homelux.co.id\/id\/products\/sliding-doors-system\/\" \/>\n<meta property=\"og:site_name\" content=\"Homelux\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/homelux.id\" \/>\n<meta property=\"article:modified_time\" content=\"2023-09-19T04:26:09+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/homelux.co.id\/wp-content\/uploads\/2022\/12\/8.-SLIM-SLIDING-WINDOW.jpg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Estimasi waktu membaca\" \/>\n\t<meta name=\"twitter:data1\" content=\"3 menit\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/homelux.co.id\\\/products\\\/sliding-doors-system\\\/\",\"url\":\"https:\\\/\\\/homelux.co.id\\\/products\\\/sliding-doors-system\\\/\",\"name\":\"Sliding doors from Homelux\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/homelux.co.id\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/homelux.co.id\\\/products\\\/sliding-doors-system\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/homelux.co.id\\\/products\\\/sliding-doors-system\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/homelux.co.id\\\/wp-content\\\/uploads\\\/2022\\\/12\\\/8.-SLIM-SLIDING-WINDOW.jpg\",\"datePublished\":\"2023-04-03T07:37:22+00:00\",\"dateModified\":\"2023-09-19T04:26:09+00:00\",\"description\":\"Sliding doors from Homelux offer a wide range of new design concepts for use indoors Homelux allows you to combine the form, function & colour\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/homelux.co.id\\\/products\\\/sliding-doors-system\\\/#breadcrumb\"},\"inLanguage\":\"id\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/homelux.co.id\\\/products\\\/sliding-doors-system\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"id\",\"@id\":\"https:\\\/\\\/homelux.co.id\\\/products\\\/sliding-doors-system\\\/#primaryimage\",\"url\":\"https:\\\/\\\/homelux.co.id\\\/wp-content\\\/uploads\\\/2022\\\/12\\\/8.-SLIM-SLIDING-WINDOW.jpg\",\"contentUrl\":\"https:\\\/\\\/homelux.co.id\\\/wp-content\\\/uploads\\\/2022\\\/12\\\/8.-SLIM-SLIDING-WINDOW.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/homelux.co.id\\\/products\\\/sliding-doors-system\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/homelux.co.id\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Products\",\"item\":\"https:\\\/\\\/homelux.co.id\\\/id\\\/products\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"homelux\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/homelux.co.id\\\/#website\",\"url\":\"https:\\\/\\\/homelux.co.id\\\/\",\"name\":\"Homelux\",\"description\":\"Home Luxurious\",\"publisher\":{\"@id\":\"https:\\\/\\\/homelux.co.id\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/homelux.co.id\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"id\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/homelux.co.id\\\/#organization\",\"name\":\"Homelux\",\"url\":\"https:\\\/\\\/homelux.co.id\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"id\",\"@id\":\"https:\\\/\\\/homelux.co.id\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/homelux.co.id\\\/wp-content\\\/uploads\\\/2022\\\/12\\\/logo-black-01.png\",\"contentUrl\":\"https:\\\/\\\/homelux.co.id\\\/wp-content\\\/uploads\\\/2022\\\/12\\\/logo-black-01.png\",\"width\":210,\"height\":63,\"caption\":\"Homelux\"},\"image\":{\"@id\":\"https:\\\/\\\/homelux.co.id\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/homelux.id\",\"https:\\\/\\\/www.instagram.com\\\/homelux.indal\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/80267481\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Sliding doors from Homelux","description":"Sliding doors from Homelux offer a wide range of new design concepts for use indoors Homelux allows you to combine the form, function & colour","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/homelux.co.id\/id\/products\/sliding-doors-system\/","og_locale":"id_ID","og_type":"article","og_title":"Sliding doors from Homelux","og_description":"Sliding doors from Homelux offer a wide range of new design concepts for use indoors Homelux allows you to combine the form, function & colour","og_url":"https:\/\/homelux.co.id\/id\/products\/sliding-doors-system\/","og_site_name":"Homelux","article_publisher":"https:\/\/www.facebook.com\/homelux.id","article_modified_time":"2023-09-19T04:26:09+00:00","og_image":[{"url":"https:\/\/homelux.co.id\/wp-content\/uploads\/2022\/12\/8.-SLIM-SLIDING-WINDOW.jpg","type":"","width":"","height":""}],"twitter_card":"summary_large_image","twitter_misc":{"Estimasi waktu membaca":"3 menit"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/homelux.co.id\/products\/sliding-doors-system\/","url":"https:\/\/homelux.co.id\/products\/sliding-doors-system\/","name":"Sliding doors from Homelux","isPartOf":{"@id":"https:\/\/homelux.co.id\/#website"},"primaryImageOfPage":{"@id":"https:\/\/homelux.co.id\/products\/sliding-doors-system\/#primaryimage"},"image":{"@id":"https:\/\/homelux.co.id\/products\/sliding-doors-system\/#primaryimage"},"thumbnailUrl":"https:\/\/homelux.co.id\/wp-content\/uploads\/2022\/12\/8.-SLIM-SLIDING-WINDOW.jpg","datePublished":"2023-04-03T07:37:22+00:00","dateModified":"2023-09-19T04:26:09+00:00","description":"Sliding doors from Homelux offer a wide range of new design concepts for use indoors Homelux allows you to combine the form, function & colour","breadcrumb":{"@id":"https:\/\/homelux.co.id\/products\/sliding-doors-system\/#breadcrumb"},"inLanguage":"id","potentialAction":[{"@type":"ReadAction","target":["https:\/\/homelux.co.id\/products\/sliding-doors-system\/"]}]},{"@type":"ImageObject","inLanguage":"id","@id":"https:\/\/homelux.co.id\/products\/sliding-doors-system\/#primaryimage","url":"https:\/\/homelux.co.id\/wp-content\/uploads\/2022\/12\/8.-SLIM-SLIDING-WINDOW.jpg","contentUrl":"https:\/\/homelux.co.id\/wp-content\/uploads\/2022\/12\/8.-SLIM-SLIDING-WINDOW.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/homelux.co.id\/products\/sliding-doors-system\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/homelux.co.id\/"},{"@type":"ListItem","position":2,"name":"Products","item":"https:\/\/homelux.co.id\/id\/products\/"},{"@type":"ListItem","position":3,"name":"homelux"}]},{"@type":"WebSite","@id":"https:\/\/homelux.co.id\/#website","url":"https:\/\/homelux.co.id\/","name":"Homelux","description":"Home Luxurious","publisher":{"@id":"https:\/\/homelux.co.id\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/homelux.co.id\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"id"},{"@type":"Organization","@id":"https:\/\/homelux.co.id\/#organization","name":"Homelux","url":"https:\/\/homelux.co.id\/","logo":{"@type":"ImageObject","inLanguage":"id","@id":"https:\/\/homelux.co.id\/#\/schema\/logo\/image\/","url":"https:\/\/homelux.co.id\/wp-content\/uploads\/2022\/12\/logo-black-01.png","contentUrl":"https:\/\/homelux.co.id\/wp-content\/uploads\/2022\/12\/logo-black-01.png","width":210,"height":63,"caption":"Homelux"},"image":{"@id":"https:\/\/homelux.co.id\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/homelux.id","https:\/\/www.instagram.com\/homelux.indal\/","https:\/\/www.linkedin.com\/company\/80267481"]}]}},"_links":{"self":[{"href":"https:\/\/homelux.co.id\/id\/wp-json\/wp\/v2\/pages\/2419","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/homelux.co.id\/id\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/homelux.co.id\/id\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/homelux.co.id\/id\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/homelux.co.id\/id\/wp-json\/wp\/v2\/comments?post=2419"}],"version-history":[{"count":159,"href":"https:\/\/homelux.co.id\/id\/wp-json\/wp\/v2\/pages\/2419\/revisions"}],"predecessor-version":[{"id":4794,"href":"https:\/\/homelux.co.id\/id\/wp-json\/wp\/v2\/pages\/2419\/revisions\/4794"}],"up":[{"embeddable":true,"href":"https:\/\/homelux.co.id\/id\/wp-json\/wp\/v2\/pages\/2460"}],"wp:attachment":[{"href":"https:\/\/homelux.co.id\/id\/wp-json\/wp\/v2\/media?parent=2419"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}